{"id":181,"count":0,"description":"","link":"https:\/\/ervy.ch\/en\/sportbekleidung\/men-boys\/underwear\/","name":"Underwear","slug":"underwear","taxonomy":"product_cat","parent":171,"meta":[],"menu_order":39,"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Underwear - Turnanz\u00fcge Made in Germany<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ervy.ch\/en\/sportbekleidung\/men-boys\/underwear\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Underwear Archive\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ervy.ch\/en\/sportbekleidung\/men-boys\/underwear\/\" \/>\n<meta property=\"og:site_name\" content=\"Turnanz\u00fcge Made in Germany\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/ervy.ch\\\/en\\\/sportbekleidung\\\/men-boys\\\/underwear\\\/\",\"url\":\"https:\\\/\\\/ervy.ch\\\/en\\\/sportbekleidung\\\/men-boys\\\/underwear\\\/\",\"name\":\"Underwear - Turnanz\u00fcge Made in Germany\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ervy.ch\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ervy.ch\\\/en\\\/sportbekleidung\\\/men-boys\\\/underwear\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ervy.ch\\\/en\\\/sportbekleidung\\\/men-boys\\\/underwear\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/ervy.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Men &amp; Boys\",\"item\":\"https:\\\/\\\/ervy.ch\\\/en\\\/sportbekleidung\\\/men-boys\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Underwear\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ervy.ch\\\/#website\",\"url\":\"https:\\\/\\\/ervy.ch\\\/\",\"name\":\"Turnanz\u00fcge Made in Germany\",\"description\":\"ERVY Schweiz-Vertretung\",\"publisher\":{\"@id\":\"https:\\\/\\\/ervy.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ervy.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ervy.ch\\\/#organization\",\"name\":\"ERVY Sports Fashion GmbH\",\"url\":\"https:\\\/\\\/ervy.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ervy.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ervy.ch\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/cropped-ERVY-Logo_JUST-SPORTS_Hintergrund_300x300.png\",\"contentUrl\":\"https:\\\/\\\/ervy.ch\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/cropped-ERVY-Logo_JUST-SPORTS_Hintergrund_300x300.png\",\"width\":512,\"height\":512,\"caption\":\"ERVY Sports Fashion GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/ervy.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ERVYSportsFashion\",\"https:\\\/\\\/www.instagram.com\\\/ervy_sports_fashion\\\/?hl=de\",\"https:\\\/\\\/www.pinterest.de\\\/ervysportsfashion\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCwzRAG_B8mAIfVPXGwfdYhA\",\"https:\\\/\\\/www.tiktok.com\\\/@ervysports\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Underwear - Turnanz\u00fcge Made in Germany","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ervy.ch\/en\/sportbekleidung\/men-boys\/underwear\/","og_locale":"en_US","og_type":"article","og_title":"Underwear Archive","og_url":"https:\/\/ervy.ch\/en\/sportbekleidung\/men-boys\/underwear\/","og_site_name":"Turnanz\u00fcge Made in Germany","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/ervy.ch\/en\/sportbekleidung\/men-boys\/underwear\/","url":"https:\/\/ervy.ch\/en\/sportbekleidung\/men-boys\/underwear\/","name":"Underwear - Turnanz\u00fcge Made in Germany","isPartOf":{"@id":"https:\/\/ervy.ch\/#website"},"breadcrumb":{"@id":"https:\/\/ervy.ch\/en\/sportbekleidung\/men-boys\/underwear\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/ervy.ch\/en\/sportbekleidung\/men-boys\/underwear\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/ervy.ch\/"},{"@type":"ListItem","position":2,"name":"Men &amp; Boys","item":"https:\/\/ervy.ch\/en\/sportbekleidung\/men-boys\/"},{"@type":"ListItem","position":3,"name":"Underwear"}]},{"@type":"WebSite","@id":"https:\/\/ervy.ch\/#website","url":"https:\/\/ervy.ch\/","name":"Turnanz\u00fcge Made in Germany","description":"ERVY Schweiz-Vertretung","publisher":{"@id":"https:\/\/ervy.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ervy.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ervy.ch\/#organization","name":"ERVY Sports Fashion GmbH","url":"https:\/\/ervy.ch\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ervy.ch\/#\/schema\/logo\/image\/","url":"https:\/\/ervy.ch\/wp-content\/uploads\/2021\/03\/cropped-ERVY-Logo_JUST-SPORTS_Hintergrund_300x300.png","contentUrl":"https:\/\/ervy.ch\/wp-content\/uploads\/2021\/03\/cropped-ERVY-Logo_JUST-SPORTS_Hintergrund_300x300.png","width":512,"height":512,"caption":"ERVY Sports Fashion GmbH"},"image":{"@id":"https:\/\/ervy.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ERVYSportsFashion","https:\/\/www.instagram.com\/ervy_sports_fashion\/?hl=de","https:\/\/www.pinterest.de\/ervysportsfashion\/","https:\/\/www.youtube.com\/channel\/UCwzRAG_B8mAIfVPXGwfdYhA","https:\/\/www.tiktok.com\/@ervysports"]}]}},"_links":{"self":[{"href":"https:\/\/ervy.ch\/en\/wp-json\/wp\/v2\/product_cat\/181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ervy.ch\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/ervy.ch\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/ervy.ch\/en\/wp-json\/wp\/v2\/product_cat\/171"}],"wp:post_type":[{"href":"https:\/\/ervy.ch\/en\/wp-json\/wp\/v2\/product?product_cat=181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}