{"id":3059,"date":"2020-09-30T12:49:33","date_gmt":"2020-09-30T10:49:33","guid":{"rendered":"https:\/\/ervy.de\/?post_type=portfolio&#038;p=3059"},"modified":"2021-03-15T11:57:32","modified_gmt":"2021-03-15T10:57:32","slug":"gymnastic-basics","status":"publish","type":"portfolio","link":"https:\/\/ervy.ch\/en\/portfolio\/gymnastic-basics\/","title":{"rendered":"Gymnastik Basics"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3059\" class=\"elementor elementor-3059\" data-elementor-post-type=\"portfolio\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1eebb2a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1eebb2a\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aa960f3\" data-id=\"aa960f3\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39f93ca elementor-widget elementor-widget-heading\" data-id=\"39f93ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Gymnastics<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17b9e56 elementor-widget elementor-widget-text-editor\" data-id=\"17b9e56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Basic Turnanz\u00fcge, Ganzanz\u00fcge, Gymbodies, Capri Tights, Hotpants, Hipster, Leggings, und vieles mehr&#8230;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-731d5cb elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"731d5cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89aabdc elementor-widget elementor-widget-heading\" data-id=\"89aabdc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">ERVY Basics Edition:<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-73c79e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"73c79e1\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-0b71105\" data-id=\"0b71105\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51c2f73 elementor-widget elementor-widget-image\" data-id=\"51c2f73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/issuu.com\/ervy\/docs\/ervy_basics_hotpants_hipster_gymshort_capri-hosen_\" target=\"_blank\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"513\" src=\"https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/Gymnastics-Basic-1024x513.jpg\" class=\"attachment-large size-large wp-image-3557\" alt=\"\" srcset=\"https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/Gymnastics-Basic-1024x513.jpg 1024w, https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/Gymnastics-Basic-600x300.jpg 600w, https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/Gymnastics-Basic-768x385.jpg 768w, https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/Gymnastics-Basic-640x321.jpg 640w, https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/Gymnastics-Basic-400x200.jpg 400w, https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/Gymnastics-Basic-367x184.jpg 367w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">ERVY Basics Edition 2011\/2012<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-638c3c4\" data-id=\"638c3c4\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-668960c elementor-widget elementor-widget-image\" data-id=\"668960c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/Gymnastics-Basic-2009.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"Gymnastics Basic 2009\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzU1OSwidXJsIjoiaHR0cHM6XC9cL2VydnkuY2hcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjBcLzA5XC9HeW1uYXN0aWNzLUJhc2ljLTIwMDkuanBnIn0%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"723\" src=\"https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/Gymnastics-Basic-2009-1024x723.jpg\" class=\"attachment-large size-large wp-image-3559\" alt=\"\" srcset=\"https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/Gymnastics-Basic-2009-1024x723.jpg 1024w, https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/Gymnastics-Basic-2009-600x424.jpg 600w, https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/Gymnastics-Basic-2009-768x542.jpg 768w, https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/Gymnastics-Basic-2009-640x452.jpg 640w, https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/Gymnastics-Basic-2009-400x282.jpg 400w, https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/Gymnastics-Basic-2009-367x259.jpg 367w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">ERVY Basics Edition 2009<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-a9310ea\" data-id=\"a9310ea\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-6a8d29b\" data-id=\"6a8d29b\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-f668e25\" data-id=\"f668e25\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-afe2dbc\" data-id=\"afe2dbc\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Basic Turnanz\u00fcge, Ganzanz\u00fcge, Gymbodies, Capri Tights, Hotpants, Hipster, Leggings, und vieles mehr&#8230;<\/p>\n","protected":false},"featured_media":3060,"comment_status":"closed","ping_status":"closed","template":"","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"portfolio_cat":[],"portfolio_skills":[],"class_list":["post-3059","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gymnastik Basics - Turnanz\u00fcge Made in Germany<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ervy.ch\/portfolio\/gymnastic-basics\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gymnastik Basics\" \/>\n<meta property=\"og:description\" content=\"Basic Turnanz\u00fcge, Ganzanz\u00fcge, Gymbodies, Capri Tights, Hotpants, Hipster, Leggings, und vieles mehr...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ervy.ch\/portfolio\/gymnastic-basics\/\" \/>\n<meta property=\"og:site_name\" content=\"Turnanz\u00fcge Made in Germany\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ERVYSportsFashion\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-15T10:57:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/Basics_3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"283\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ervy.ch\\\/portfolio\\\/gymnastic-basics\\\/\",\"url\":\"https:\\\/\\\/ervy.ch\\\/portfolio\\\/gymnastic-basics\\\/\",\"name\":\"Gymnastik Basics - Turnanz\u00fcge Made in Germany\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ervy.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ervy.ch\\\/portfolio\\\/gymnastic-basics\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ervy.ch\\\/portfolio\\\/gymnastic-basics\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ervy.ch\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Basics_3.jpg\",\"datePublished\":\"2020-09-30T10:49:33+00:00\",\"dateModified\":\"2021-03-15T10:57:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ervy.ch\\\/portfolio\\\/gymnastic-basics\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ervy.ch\\\/portfolio\\\/gymnastic-basics\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ervy.ch\\\/portfolio\\\/gymnastic-basics\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ervy.ch\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Basics_3.jpg\",\"contentUrl\":\"https:\\\/\\\/ervy.ch\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Basics_3.jpg\",\"width\":283,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ervy.ch\\\/portfolio\\\/gymnastic-basics\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/ervy.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolios\",\"item\":\"https:\\\/\\\/ervy.ch\\\/portfolio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gymnastik Basics\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ervy.ch\\\/#website\",\"url\":\"https:\\\/\\\/ervy.ch\\\/\",\"name\":\"Turnanz\u00fcge Made in Germany\",\"description\":\"ERVY Schweiz-Vertretung\",\"publisher\":{\"@id\":\"https:\\\/\\\/ervy.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ervy.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ervy.ch\\\/#organization\",\"name\":\"ERVY Sports Fashion GmbH\",\"url\":\"https:\\\/\\\/ervy.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ervy.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ervy.ch\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/cropped-ERVY-Logo_JUST-SPORTS_Hintergrund_300x300.png\",\"contentUrl\":\"https:\\\/\\\/ervy.ch\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/cropped-ERVY-Logo_JUST-SPORTS_Hintergrund_300x300.png\",\"width\":512,\"height\":512,\"caption\":\"ERVY Sports Fashion GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/ervy.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ERVYSportsFashion\",\"https:\\\/\\\/www.instagram.com\\\/ervy_sports_fashion\\\/?hl=de\",\"https:\\\/\\\/www.pinterest.de\\\/ervysportsfashion\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCwzRAG_B8mAIfVPXGwfdYhA\",\"https:\\\/\\\/www.tiktok.com\\\/@ervysports\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gymnastik Basics - Turnanz\u00fcge Made in Germany","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ervy.ch\/portfolio\/gymnastic-basics\/","og_locale":"en_US","og_type":"article","og_title":"Gymnastik Basics","og_description":"Basic Turnanz\u00fcge, Ganzanz\u00fcge, Gymbodies, Capri Tights, Hotpants, Hipster, Leggings, und vieles mehr...","og_url":"https:\/\/ervy.ch\/portfolio\/gymnastic-basics\/","og_site_name":"Turnanz\u00fcge Made in Germany","article_publisher":"https:\/\/www.facebook.com\/ERVYSportsFashion","article_modified_time":"2021-03-15T10:57:32+00:00","og_image":[{"width":283,"height":400,"url":"https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/Basics_3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ervy.ch\/portfolio\/gymnastic-basics\/","url":"https:\/\/ervy.ch\/portfolio\/gymnastic-basics\/","name":"Gymnastik Basics - Turnanz\u00fcge Made in Germany","isPartOf":{"@id":"https:\/\/ervy.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ervy.ch\/portfolio\/gymnastic-basics\/#primaryimage"},"image":{"@id":"https:\/\/ervy.ch\/portfolio\/gymnastic-basics\/#primaryimage"},"thumbnailUrl":"https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/Basics_3.jpg","datePublished":"2020-09-30T10:49:33+00:00","dateModified":"2021-03-15T10:57:32+00:00","breadcrumb":{"@id":"https:\/\/ervy.ch\/portfolio\/gymnastic-basics\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ervy.ch\/portfolio\/gymnastic-basics\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ervy.ch\/portfolio\/gymnastic-basics\/#primaryimage","url":"https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/Basics_3.jpg","contentUrl":"https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/Basics_3.jpg","width":283,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/ervy.ch\/portfolio\/gymnastic-basics\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/ervy.ch\/"},{"@type":"ListItem","position":2,"name":"Portfolios","item":"https:\/\/ervy.ch\/portfolio\/"},{"@type":"ListItem","position":3,"name":"Gymnastik Basics"}]},{"@type":"WebSite","@id":"https:\/\/ervy.ch\/#website","url":"https:\/\/ervy.ch\/","name":"Turnanz\u00fcge Made in Germany","description":"ERVY Schweiz-Vertretung","publisher":{"@id":"https:\/\/ervy.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ervy.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ervy.ch\/#organization","name":"ERVY Sports Fashion GmbH","url":"https:\/\/ervy.ch\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ervy.ch\/#\/schema\/logo\/image\/","url":"https:\/\/ervy.ch\/wp-content\/uploads\/2021\/03\/cropped-ERVY-Logo_JUST-SPORTS_Hintergrund_300x300.png","contentUrl":"https:\/\/ervy.ch\/wp-content\/uploads\/2021\/03\/cropped-ERVY-Logo_JUST-SPORTS_Hintergrund_300x300.png","width":512,"height":512,"caption":"ERVY Sports Fashion GmbH"},"image":{"@id":"https:\/\/ervy.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ERVYSportsFashion","https:\/\/www.instagram.com\/ervy_sports_fashion\/?hl=de","https:\/\/www.pinterest.de\/ervysportsfashion\/","https:\/\/www.youtube.com\/channel\/UCwzRAG_B8mAIfVPXGwfdYhA","https:\/\/www.tiktok.com\/@ervysports"]}]}},"_links":{"self":[{"href":"https:\/\/ervy.ch\/en\/wp-json\/wp\/v2\/portfolio\/3059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ervy.ch\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/ervy.ch\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"replies":[{"embeddable":true,"href":"https:\/\/ervy.ch\/en\/wp-json\/wp\/v2\/comments?post=3059"}],"version-history":[{"count":0,"href":"https:\/\/ervy.ch\/en\/wp-json\/wp\/v2\/portfolio\/3059\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ervy.ch\/en\/wp-json\/wp\/v2\/media\/3060"}],"wp:attachment":[{"href":"https:\/\/ervy.ch\/en\/wp-json\/wp\/v2\/media?parent=3059"}],"wp:term":[{"taxonomy":"portfolio_cat","embeddable":true,"href":"https:\/\/ervy.ch\/en\/wp-json\/wp\/v2\/portfolio_cat?post=3059"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/ervy.ch\/en\/wp-json\/wp\/v2\/portfolio_skills?post=3059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}