{"id":3049,"date":"2020-09-30T12:44:23","date_gmt":"2020-09-30T10:44:23","guid":{"rendered":"https:\/\/ervy.de\/?post_type=portfolio&#038;p=3049"},"modified":"2021-03-12T14:19:54","modified_gmt":"2021-03-12T13:19:54","slug":"unitards","status":"publish","type":"portfolio","link":"https:\/\/ervy.ch\/en\/portfolio\/unitards\/","title":{"rendered":"Unitards"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3049\" class=\"elementor elementor-3049\" data-elementor-post-type=\"portfolio\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a4c68f3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a4c68f3\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a185d56\" data-id=\"a185d56\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d6c5430 elementor-widget elementor-widget-heading\" data-id=\"d6c5430\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ERVY Voltigieren und TeamGym<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-794738f elementor-widget elementor-widget-text-editor\" data-id=\"794738f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Voltigieranz\u00fcge, Ganzanz\u00fcge, Catsuits, Overalls<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a7c44a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a7c44a\" data-element_type=\"section\" data-e-type=\"section\">\r\n\t\t\r\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\r\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-a5b240c\" data-id=\"a5b240c\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d3afdab elementor-widget elementor-widget-image\" data-id=\"d3afdab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/issuu.com\/ervy\/docs\/ervy_unitards_2011-2012_unitard_voltigieren_teamgy\" target=\"_blank\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/ERVY_Katalog_Unitard-Edition_2011-2012_TITELSEITE-1024x1024.jpg\" class=\"attachment-large size-large wp-image-3537\" alt=\"\" srcset=\"https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/ERVY_Katalog_Unitard-Edition_2011-2012_TITELSEITE-1024x1024.jpg 1024w, https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/ERVY_Katalog_Unitard-Edition_2011-2012_TITELSEITE-600x600.jpg 600w, https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/ERVY_Katalog_Unitard-Edition_2011-2012_TITELSEITE-768x768.jpg 768w, https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/ERVY_Katalog_Unitard-Edition_2011-2012_TITELSEITE-640x640.jpg 640w, https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/ERVY_Katalog_Unitard-Edition_2011-2012_TITELSEITE-400x400.jpg 400w, https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/ERVY_Katalog_Unitard-Edition_2011-2012_TITELSEITE-560x560.jpg 560w, https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/ERVY_Katalog_Unitard-Edition_2011-2012_TITELSEITE-367x367.jpg 367w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">ERVY Unitard Edition 2011\/2012<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-5fc290f\" data-id=\"5fc290f\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62f2de6 elementor-widget elementor-widget-image\" data-id=\"62f2de6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/Voltigieranzuege.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"Voltigieranz\u00fcge\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzUzOSwidXJsIjoiaHR0cHM6XC9cL2VydnkuY2hcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjBcLzA5XC9Wb2x0aWdpZXJhbnp1ZWdlLmpwZyJ9\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"839\" height=\"596\" src=\"https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/Voltigieranzuege.jpg\" class=\"attachment-large size-large wp-image-3539\" alt=\"\" srcset=\"https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/Voltigieranzuege.jpg 839w, https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/Voltigieranzuege-600x426.jpg 600w, https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/Voltigieranzuege-768x546.jpg 768w, https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/Voltigieranzuege-640x455.jpg 640w, https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/Voltigieranzuege-400x284.jpg 400w, https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/Voltigieranzuege-367x261.jpg 367w\" sizes=\"(max-width: 839px) 100vw, 839px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">ERVY Voltigieranz\u00fcge Flyer 2009<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-19dd01e\" data-id=\"19dd01e\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-35edde5\" data-id=\"35edde5\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-09b45d8\" data-id=\"09b45d8\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-0e1de00\" data-id=\"0e1de00\" data-element_type=\"column\" data-e-type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Voltigieranz\u00fcge, Ganzanz\u00fcge, Catsuits, Overalls<\/p>\n","protected":false},"featured_media":3047,"comment_status":"closed","ping_status":"closed","template":"","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"portfolio_cat":[],"portfolio_skills":[],"class_list":["post-3049","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Unitards - Turnanz\u00fcge Made in Germany<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ervy.ch\/portfolio\/unitards\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unitards\" \/>\n<meta property=\"og:description\" content=\"Voltigieranz\u00fcge, Ganzanz\u00fcge, Catsuits, Overalls\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ervy.ch\/portfolio\/unitards\/\" \/>\n<meta property=\"og:site_name\" content=\"Turnanz\u00fcge Made in Germany\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ERVYSportsFashion\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-12T13:19:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/Naranja.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"370\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ervy.ch\\\/portfolio\\\/unitards\\\/\",\"url\":\"https:\\\/\\\/ervy.ch\\\/portfolio\\\/unitards\\\/\",\"name\":\"Unitards - Turnanz\u00fcge Made in Germany\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ervy.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ervy.ch\\\/portfolio\\\/unitards\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ervy.ch\\\/portfolio\\\/unitards\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ervy.ch\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Naranja.jpg\",\"datePublished\":\"2020-09-30T10:44:23+00:00\",\"dateModified\":\"2021-03-12T13:19:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ervy.ch\\\/portfolio\\\/unitards\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ervy.ch\\\/portfolio\\\/unitards\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ervy.ch\\\/portfolio\\\/unitards\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ervy.ch\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Naranja.jpg\",\"contentUrl\":\"https:\\\/\\\/ervy.ch\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Naranja.jpg\",\"width\":370,\"height\":1000,\"caption\":\"Ganzanzug NARANJA von ERVY hergestellt in Deutschland\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ervy.ch\\\/portfolio\\\/unitards\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/ervy.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolios\",\"item\":\"https:\\\/\\\/ervy.ch\\\/portfolio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Unitards\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ervy.ch\\\/#website\",\"url\":\"https:\\\/\\\/ervy.ch\\\/\",\"name\":\"Turnanz\u00fcge Made in Germany\",\"description\":\"ERVY Schweiz-Vertretung\",\"publisher\":{\"@id\":\"https:\\\/\\\/ervy.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ervy.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ervy.ch\\\/#organization\",\"name\":\"ERVY Sports Fashion GmbH\",\"url\":\"https:\\\/\\\/ervy.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ervy.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ervy.ch\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/cropped-ERVY-Logo_JUST-SPORTS_Hintergrund_300x300.png\",\"contentUrl\":\"https:\\\/\\\/ervy.ch\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/cropped-ERVY-Logo_JUST-SPORTS_Hintergrund_300x300.png\",\"width\":512,\"height\":512,\"caption\":\"ERVY Sports Fashion GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/ervy.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ERVYSportsFashion\",\"https:\\\/\\\/www.instagram.com\\\/ervy_sports_fashion\\\/?hl=de\",\"https:\\\/\\\/www.pinterest.de\\\/ervysportsfashion\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCwzRAG_B8mAIfVPXGwfdYhA\",\"https:\\\/\\\/www.tiktok.com\\\/@ervysports\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Unitards - Turnanz\u00fcge Made in Germany","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ervy.ch\/portfolio\/unitards\/","og_locale":"en_US","og_type":"article","og_title":"Unitards","og_description":"Voltigieranz\u00fcge, Ganzanz\u00fcge, Catsuits, Overalls","og_url":"https:\/\/ervy.ch\/portfolio\/unitards\/","og_site_name":"Turnanz\u00fcge Made in Germany","article_publisher":"https:\/\/www.facebook.com\/ERVYSportsFashion","article_modified_time":"2021-03-12T13:19:54+00:00","og_image":[{"width":370,"height":1000,"url":"https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/Naranja.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ervy.ch\/portfolio\/unitards\/","url":"https:\/\/ervy.ch\/portfolio\/unitards\/","name":"Unitards - Turnanz\u00fcge Made in Germany","isPartOf":{"@id":"https:\/\/ervy.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ervy.ch\/portfolio\/unitards\/#primaryimage"},"image":{"@id":"https:\/\/ervy.ch\/portfolio\/unitards\/#primaryimage"},"thumbnailUrl":"https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/Naranja.jpg","datePublished":"2020-09-30T10:44:23+00:00","dateModified":"2021-03-12T13:19:54+00:00","breadcrumb":{"@id":"https:\/\/ervy.ch\/portfolio\/unitards\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ervy.ch\/portfolio\/unitards\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ervy.ch\/portfolio\/unitards\/#primaryimage","url":"https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/Naranja.jpg","contentUrl":"https:\/\/ervy.ch\/wp-content\/uploads\/2020\/09\/Naranja.jpg","width":370,"height":1000,"caption":"Ganzanzug NARANJA von ERVY hergestellt in Deutschland"},{"@type":"BreadcrumbList","@id":"https:\/\/ervy.ch\/portfolio\/unitards\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/ervy.ch\/"},{"@type":"ListItem","position":2,"name":"Portfolios","item":"https:\/\/ervy.ch\/portfolio\/"},{"@type":"ListItem","position":3,"name":"Unitards"}]},{"@type":"WebSite","@id":"https:\/\/ervy.ch\/#website","url":"https:\/\/ervy.ch\/","name":"Turnanz\u00fcge Made in Germany","description":"ERVY Schweiz-Vertretung","publisher":{"@id":"https:\/\/ervy.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ervy.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ervy.ch\/#organization","name":"ERVY Sports Fashion GmbH","url":"https:\/\/ervy.ch\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ervy.ch\/#\/schema\/logo\/image\/","url":"https:\/\/ervy.ch\/wp-content\/uploads\/2021\/03\/cropped-ERVY-Logo_JUST-SPORTS_Hintergrund_300x300.png","contentUrl":"https:\/\/ervy.ch\/wp-content\/uploads\/2021\/03\/cropped-ERVY-Logo_JUST-SPORTS_Hintergrund_300x300.png","width":512,"height":512,"caption":"ERVY Sports Fashion GmbH"},"image":{"@id":"https:\/\/ervy.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ERVYSportsFashion","https:\/\/www.instagram.com\/ervy_sports_fashion\/?hl=de","https:\/\/www.pinterest.de\/ervysportsfashion\/","https:\/\/www.youtube.com\/channel\/UCwzRAG_B8mAIfVPXGwfdYhA","https:\/\/www.tiktok.com\/@ervysports"]}]}},"_links":{"self":[{"href":"https:\/\/ervy.ch\/en\/wp-json\/wp\/v2\/portfolio\/3049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ervy.ch\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/ervy.ch\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"replies":[{"embeddable":true,"href":"https:\/\/ervy.ch\/en\/wp-json\/wp\/v2\/comments?post=3049"}],"version-history":[{"count":0,"href":"https:\/\/ervy.ch\/en\/wp-json\/wp\/v2\/portfolio\/3049\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ervy.ch\/en\/wp-json\/wp\/v2\/media\/3047"}],"wp:attachment":[{"href":"https:\/\/ervy.ch\/en\/wp-json\/wp\/v2\/media?parent=3049"}],"wp:term":[{"taxonomy":"portfolio_cat","embeddable":true,"href":"https:\/\/ervy.ch\/en\/wp-json\/wp\/v2\/portfolio_cat?post=3049"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/ervy.ch\/en\/wp-json\/wp\/v2\/portfolio_skills?post=3049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}